{"id":15676,"date":"2021-06-03T23:05:22","date_gmt":"2021-06-03T21:05:22","guid":{"rendered":"https:\/\/www.vetinox.fr\/empresa\/"},"modified":"2024-05-20T16:27:34","modified_gmt":"2024-05-20T14:27:34","slug":"empresa","status":"publish","type":"page","link":"https:\/\/www.vetinox.fr\/es\/empresa\/","title":{"rendered":"Empresa"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"15676\" class=\"elementor elementor-15676 elementor-97\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c469cd3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c469cd3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27b1c09\" data-id=\"27b1c09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57cd597 elementor-widget elementor-widget-heading\" data-id=\"57cd597\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">El especialista en equipos a uso veterinario<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3298366 elementor-widget elementor-widget-text-editor\" data-id=\"3298366\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Desde hace m\u00e1s de 34 a\u00f1os, Vetinox es el especialista franc\u00e9s en equipos y materiales veterinarios dedicados a los profesionales de la salud animal.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a8d866 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a8d866\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64240a7\" data-id=\"64240a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bde09b4 elementor-widget elementor-widget-image\" data-id=\"bde09b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"744\" height=\"760\" src=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/12\/Chien-sur-table-veterinaire-1.jpg\" class=\"attachment-large size-large wp-image-15694\" alt=\"mat\u00e9riel v\u00e9t\u00e9rinaire\" srcset=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/12\/Chien-sur-table-veterinaire-1.jpg 744w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/12\/Chien-sur-table-veterinaire-1-294x300.jpg 294w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/12\/Chien-sur-table-veterinaire-1-600x613.jpg 600w\" sizes=\"(max-width: 744px) 100vw, 744px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78ba9c2\" data-id=\"78ba9c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c26dd8 elementor-widget elementor-widget-heading\" data-id=\"5c26dd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La referencia francesa <br>en material veterinario<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ce5be9 elementor-widget elementor-widget-text-editor\" data-id=\"3ce5be9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Como cada consulta, cl\u00ednica o asociaci\u00f3n es \u00fanica, fabricamos equipos veterinarios a medida. Todos nuestros productos se pueden adaptar y personalizar seg\u00fan sus necesidades y deseos.<\/p>\n<p>Para ello, basta con que nos comunique sus dimensiones y la disposici\u00f3n deseada. Estaremos encantados de ayudarle con su proyecto.<\/p>\n<p>Nuestros equipos le asesorar\u00e1n y acompa\u00f1ar\u00e1n en el manejo de su equipo veterinario, as\u00ed como en su uso diario. Usted beneficia de un servicio postventa para plantear cualquier cuesti\u00f3n, y su equipo est\u00e1, por supuesto, garantizado en caso de anomal\u00eda.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b4047f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2b4047f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0039af8\" data-id=\"0039af8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1633068 elementor-widget elementor-widget-heading\" data-id=\"1633068\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Experiencia que perdura y evoluciona con los a\u00f1os<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27feca37 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27feca37\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4bb9dd75\" data-id=\"4bb9dd75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c4c489 elementor-widget elementor-widget-image\" data-id=\"8c4c489\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/12\/people-at-work2.jpg\" class=\"attachment-large size-large wp-image-15695\" alt=\"expert mat\u00e9riel v\u00e9t\u00e9rinaire\" srcset=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/12\/people-at-work2.jpg 500w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/12\/people-at-work2-200x300.jpg 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7170e8eb\" data-id=\"7170e8eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-109a8393 elementor-widget elementor-widget-text-editor\" data-id=\"109a8393\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La aventura comenz\u00f3 en 1984 y, desde entonces, Vetinox no ha dejado de desplegar su pasi\u00f3n y profesionalismo al servicio de sus clientes.<\/p>\n<p>Con un equipo de profesionales expertos en equipos veterinarios desde sus inicios, producimos y comercializamos productos que se mejoran continuamente. A lo largo de estos a\u00f1os, la empresa no ha hecho m\u00e1s que reforzar su conocimiento y la alta calidad de sus productos.<\/p>\n<p>A finales de 2018, un punto de inflexi\u00f3n para Vetinox que se beneficia de un cambio de propiedad y, al mismo tiempo, de un cambio estrat\u00e9gico. \u00bfEl objetivo? Responder lo mejor posible a los retos y necesidades del mercado veterinario.<\/p>\n<p>Los equipos dedicados a la investigaci\u00f3n y la innovaci\u00f3n nos permiten desarrollar gamas \u00fanicas de equipos veterinarios. Como expertos en el mercado, pensamos y dise\u00f1amos productos pensados para mejorar la comodidad y el trabajo de los profesionales de la salud animal.<\/p>\n<p>Este nuevo paso estructural tambi\u00e9n pretende desarrollar nuestras actividades hacia los mercados internacionales en los pr\u00f3ximos a\u00f1os.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0186866 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0186866\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c3e2547\" data-id=\"c3e2547\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f9aa9b elementor-widget elementor-widget-heading\" data-id=\"0f9aa9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Una nueva planta <br>para el dise\u00f1o de equipos veterinarios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-042cd8b elementor-widget elementor-widget-text-editor\" data-id=\"042cd8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tambi\u00e9n en este contexto, en 2021 se pondr\u00e1 en marcha un innovador proyecto de f\u00e1brica, dise\u00f1ado para la comodidad y el bienestar de los empleados.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64069d4\" data-id=\"64069d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b37703c elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"b37703c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/elementor\/thumbs\/save-1-ozj6xdt1ssb46ep3eyt2tcvn6k0uiorrr0a5471bfk.png\" title=\"eco responsable\" alt=\"eco responsable\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Comprometidos y eco-responsables<\/h3><p class=\"elementor-image-box-description\">La planta utilizar\u00e1 una fuente de energ\u00eda verde 100% renovable garantizada, respetando el compromiso con la transici\u00f3n hacia el carbono cero.     <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb0494a elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"fb0494a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/elementor\/thumbs\/ear-ozj7ko93506vukv7f18alhat29898p8caa7970i59c.png\" title=\"traitement acoustique\" alt=\"traitement acoustique\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Adaptado a la comodidad de los empleados<\/h3><p class=\"elementor-image-box-description\">Las instalaciones se beneficiar\u00e1n de un tratamiento ac\u00fastico para reducir la contaminaci\u00f3n ac\u00fastica y crear un entorno de trabajo m\u00e1s agradable.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c05fa9f elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"c05fa9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/elementor\/thumbs\/sketch-ozkpy7yy6xxcrff3pp0nu009req4k5k6f8tmd810yo.png\" title=\"plan usine pour \u00e9quipement v\u00e9t\u00e9rinaire\" alt=\"plan usine pour \u00e9quipement v\u00e9t\u00e9rinaire\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Amueblado con grandes espacios<\/h3><p class=\"elementor-image-box-description\">Los espacios se han dise\u00f1ado para facilitar la circulaci\u00f3n y optimizar los puestos de trabajo, mejorando as\u00ed la seguridad de los empleados.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19b0399 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"19b0399\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/elementor\/thumbs\/laser-cutting-machine-ozj8f64kvhxsj4khc7sjhs96wawyz6att86dq7abds.png\" title=\"machine pour mat\u00e9riel v\u00e9t\u00e9rinaire\" alt=\"machine pour mat\u00e9riel v\u00e9t\u00e9rinaire\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Equipado con m\u00e1quinas digitales<\/h3><p class=\"elementor-image-box-description\">Nuestra f\u00e1brica estar\u00e1 equipada con m\u00e1quinas digitales con asistencia a la producci\u00f3n para limitar los esfuerzos de los empleados, reducir su cansancio y aumentar la precisi\u00f3n del acabado.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cbdce44 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cbdce44\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b6fe91\" data-id=\"3b6fe91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdcc349 elementor-widget elementor-widget-spacer\" data-id=\"bdcc349\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-393bdb7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"393bdb7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20d42ce\" data-id=\"20d42ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b255b9 elementor-widget elementor-widget-heading\" data-id=\"0b255b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestras cifras clave<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9775432 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9775432\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0d4bf02\" data-id=\"0d4bf02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26b6321 elementor-widget elementor-widget-counter\" data-id=\"26b6321\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Personal experto<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"15\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a1d12c7\" data-id=\"a1d12c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d72c318 elementor-widget elementor-widget-counter\" data-id=\"d72c318\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">A\u00f1os de experiencia<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"40\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-afbcaa0\" data-id=\"afbcaa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc55522 elementor-widget elementor-widget-counter\" data-id=\"dc55522\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Centro de producci\u00f3n franc\u00e9s<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0fff32e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0fff32e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44721ca\" data-id=\"44721ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a2bfd4 elementor-widget elementor-widget-heading\" data-id=\"9a2bfd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestras \u00faltimas noticias<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a16c2d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a16c2d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e5353fb\" data-id=\"7e5353fb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f47b764 elementor-posts--align-center elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"1f47b764\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-17016 post type-post status-publish format-standard has-post-thumbnail hentry entry has-media owp-thumbs-layout-vertical owp-btn-normal owp-tabs-layout-horizontal has-no-thumbnails has-product-nav\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.vetinox.fr\/es\/como-mantener-su-equipo-vetinox\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"992\" height=\"519\" src=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/Capture.jpg\" class=\"attachment-full size-full wp-image-17017\" alt=\"entretenir mat\u00e9riel v\u00e9t\u00e9rinaire\" srcset=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/Capture.jpg 992w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/Capture-300x157.jpg 300w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/Capture-768x402.jpg 768w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/Capture-600x314.jpg 600w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.vetinox.fr\/es\/como-mantener-su-equipo-vetinox\/\" >\n\t\t\t\t\u00bfC\u00f3mo mantener su equipo Vetinox?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Descubra c\u00f3mo limpiar su equipo veterinario de acero inoxidable Ya sean nuestras mesas, jaulas o equipos veterinarios, todos nuestros productos son de acero inoxidable. Robusto,<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.vetinox.fr\/es\/como-mantener-su-equipo-vetinox\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre \u00bfC\u00f3mo mantener su equipo Vetinox?\" tabindex=\"-1\" >\n\t\t\tLEER LA NOTICIA \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t21 de junio de 2021\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-17012 post type-post status-publish format-standard has-post-thumbnail hentry entry has-media owp-thumbs-layout-vertical owp-btn-normal owp-tabs-layout-horizontal has-no-thumbnails has-product-nav\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.vetinox.fr\/es\/vetinox-lanza-la-primera-mesa-veterinaria-ultra-baja\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/Table-veterinaire-ultra-basse.png\" class=\"attachment-full size-full wp-image-17013\" alt=\"Table veterinaire ultra basse\" srcset=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/Table-veterinaire-ultra-basse.png 1200w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/Table-veterinaire-ultra-basse-300x200.png 300w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/Table-veterinaire-ultra-basse-1024x683.png 1024w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/Table-veterinaire-ultra-basse-768x512.png 768w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/Table-veterinaire-ultra-basse-600x400.png 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.vetinox.fr\/es\/vetinox-lanza-la-primera-mesa-veterinaria-ultra-baja\/\" >\n\t\t\t\tVETINOX lanza la primera mesa veterinaria ultra baja\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>la gama de mesas de consulta elite: una verdadera innovaci\u00f3n en el ambito veterinario Vetinox lanza una nueva gama de mesas ultra vers\u00e1tiles, dise\u00f1adas para<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.vetinox.fr\/es\/vetinox-lanza-la-primera-mesa-veterinaria-ultra-baja\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre VETINOX lanza la primera mesa veterinaria ultra baja\" tabindex=\"-1\" >\n\t\t\tLEER LA NOTICIA \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t21 de junio de 2021\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-17006 post type-post status-publish format-standard has-post-thumbnail hentry entry has-media owp-thumbs-layout-vertical owp-btn-normal owp-tabs-layout-horizontal has-no-thumbnails has-product-nav\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.vetinox.fr\/es\/vetinox-consume-electricidad-verde\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1362\" src=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/O7MEZA0-scaled.jpg\" class=\"attachment-full size-full wp-image-17008\" alt=\"electricite verte\" srcset=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/O7MEZA0-scaled.jpg 2048w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/O7MEZA0-300x199.jpg 300w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/O7MEZA0-1024x681.jpg 1024w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/O7MEZA0-768x511.jpg 768w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/O7MEZA0-1536x1021.jpg 1536w, https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/09\/O7MEZA0-600x399.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.vetinox.fr\/es\/vetinox-consume-electricidad-verde\/\" >\n\t\t\t\tVETINOX consume electricidad verde\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Firmemente comprometidos con la transici\u00f3n hacia el carbono cero, actuamos a favor del clima y elegimos electricidad de producci\u00f3n 100% renovable garantizada.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.vetinox.fr\/es\/vetinox-consume-electricidad-verde\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre VETINOX consume electricidad verde\" tabindex=\"-1\" >\n\t\t\tLEER LA NOTICIA \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t21 de junio de 2021\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El especialista en equipos a uso veterinario Desde hace m\u00e1s de 34 a\u00f1os, Vetinox es el especialista franc\u00e9s en equipos y materiales veterinarios dedicados a los profesionales de la salud animal. La referencia francesa en material veterinario Como cada consulta, cl\u00ednica o asociaci\u00f3n es \u00fanica, fabricamos equipos veterinarios a medida. Todos nuestros productos se pueden [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"on","ocean_display_header":"on","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"Empresa Vetinox","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-15676","page","type-page","status-publish","hentry","entry","has-media","owp-thumbs-layout-vertical","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La referencia francesa para los equipos veterinarios - Vetinox<\/title>\n<meta name=\"description\" content=\"Desde hace m\u00e1s de 34 a\u00f1os, producimos equipos veterinarios de alta calidad para los profesionales de la salud animal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vetinox.fr\/societe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La referencia francesa para los equipos veterinarios - Vetinox\" \/>\n<meta property=\"og:description\" content=\"Desde hace m\u00e1s de 34 a\u00f1os, producimos equipos veterinarios de alta calidad para los profesionales de la salud animal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetinox.fr\/societe\/\" \/>\n<meta property=\"og:site_name\" content=\"Vetinox\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-20T14:27:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/12\/Chien-sur-table-veterinaire-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetinox.fr\\\/societe\\\/\",\"url\":\"https:\\\/\\\/www.vetinox.fr\\\/societe\\\/\",\"name\":\"La referencia francesa para los equipos veterinarios - Vetinox\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetinox.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetinox.fr\\\/societe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetinox.fr\\\/societe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetinox.fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Chien-sur-table-veterinaire-1.jpg\",\"datePublished\":\"2021-06-03T21:05:22+00:00\",\"dateModified\":\"2024-05-20T14:27:34+00:00\",\"description\":\"Desde hace m\u00e1s de 34 a\u00f1os, producimos equipos veterinarios de alta calidad para los profesionales de la salud animal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetinox.fr\\\/societe\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetinox.fr\\\/societe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.vetinox.fr\\\/societe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetinox.fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Chien-sur-table-veterinaire-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetinox.fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Chien-sur-table-veterinaire-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetinox.fr\\\/societe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetinox.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetinox.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.vetinox.fr\\\/\",\"name\":\"Vetinox\",\"description\":\"Equipement Veterinaire\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetinox.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetinox.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetinox.fr\\\/#organization\",\"name\":\"Vetinox\",\"url\":\"https:\\\/\\\/www.vetinox.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.vetinox.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetinox.fr\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Logo-Vetinox-2.png\",\"contentUrl\":\"https:\\\/\\\/www.vetinox.fr\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Logo-Vetinox-2.png\",\"width\":414,\"height\":126,\"caption\":\"Vetinox\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetinox.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La referencia francesa para los equipos veterinarios - Vetinox","description":"Desde hace m\u00e1s de 34 a\u00f1os, producimos equipos veterinarios de alta calidad para los profesionales de la salud animal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vetinox.fr\/societe\/","og_locale":"es_ES","og_type":"article","og_title":"La referencia francesa para los equipos veterinarios - Vetinox","og_description":"Desde hace m\u00e1s de 34 a\u00f1os, producimos equipos veterinarios de alta calidad para los profesionales de la salud animal.","og_url":"https:\/\/www.vetinox.fr\/societe\/","og_site_name":"Vetinox","article_modified_time":"2024-05-20T14:27:34+00:00","og_image":[{"url":"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/12\/Chien-sur-table-veterinaire-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetinox.fr\/societe\/","url":"https:\/\/www.vetinox.fr\/societe\/","name":"La referencia francesa para los equipos veterinarios - Vetinox","isPartOf":{"@id":"https:\/\/www.vetinox.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetinox.fr\/societe\/#primaryimage"},"image":{"@id":"https:\/\/www.vetinox.fr\/societe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/12\/Chien-sur-table-veterinaire-1.jpg","datePublished":"2021-06-03T21:05:22+00:00","dateModified":"2024-05-20T14:27:34+00:00","description":"Desde hace m\u00e1s de 34 a\u00f1os, producimos equipos veterinarios de alta calidad para los profesionales de la salud animal.","breadcrumb":{"@id":"https:\/\/www.vetinox.fr\/societe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetinox.fr\/societe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.vetinox.fr\/societe\/#primaryimage","url":"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/12\/Chien-sur-table-veterinaire-1.jpg","contentUrl":"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2020\/12\/Chien-sur-table-veterinaire-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetinox.fr\/societe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetinox.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Empresa"}]},{"@type":"WebSite","@id":"https:\/\/www.vetinox.fr\/#website","url":"https:\/\/www.vetinox.fr\/","name":"Vetinox","description":"Equipement Veterinaire","publisher":{"@id":"https:\/\/www.vetinox.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetinox.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.vetinox.fr\/#organization","name":"Vetinox","url":"https:\/\/www.vetinox.fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.vetinox.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2018\/11\/Logo-Vetinox-2.png","contentUrl":"https:\/\/www.vetinox.fr\/wp-content\/uploads\/2018\/11\/Logo-Vetinox-2.png","width":414,"height":126,"caption":"Vetinox"},"image":{"@id":"https:\/\/www.vetinox.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.vetinox.fr\/es\/wp-json\/wp\/v2\/pages\/15676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetinox.fr\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vetinox.fr\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetinox.fr\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetinox.fr\/es\/wp-json\/wp\/v2\/comments?post=15676"}],"version-history":[{"count":0,"href":"https:\/\/www.vetinox.fr\/es\/wp-json\/wp\/v2\/pages\/15676\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vetinox.fr\/es\/wp-json\/wp\/v2\/media?parent=15676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}